{"id":447,"date":"2021-03-02T08:21:56","date_gmt":"2021-03-02T08:21:56","guid":{"rendered":"https:\/\/genomefrontier.com\/?post_type=portfolio&#038;p=447"},"modified":"2026-04-13T08:05:03","modified_gmt":"2026-04-13T08:05:03","slug":"news012","status":"publish","type":"portfolio","link":"https:\/\/genomefrontier.com\/zh\/portfolio-item\/news012\/","title":{"rendered":"\u5148\u9a45\u751f\u6280\u591a\u9805\u767c\u660e \u7372\u570b\u969b\u95dc\u6ce8 \/ \u4e2d\u6642\u5831\u5c0e"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"menu_order":0,"comment_status":"open","ping_status":"closed","template":"","meta":{"_coblocks_attr":"","_coblocks_dimensions":"","_coblocks_responsive_height":"","_coblocks_accordion_ie_support":""},"portfolio-types":[],"class_list":["post-447","portfolio","type-portfolio","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\u5148\u9a45\u751f\u6280\u591a\u9805\u767c\u660e \u7372\u570b\u969b\u95dc\u6ce8 \/ \u4e2d\u6642\u5831\u5c0e - GenomeFrontier Therapeutics, Inc. \u5148\u9a45\u751f\u6280<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/genomefrontier.com\/zh\/portfolio-item\/news012\/\" \/>\n<meta property=\"og:locale\" content=\"zh_TW\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u5148\u9a45\u751f\u6280\u591a\u9805\u767c\u660e \u7372\u570b\u969b\u95dc\u6ce8 \/ \u4e2d\u6642\u5831\u5c0e - GenomeFrontier Therapeutics, Inc. \u5148\u9a45\u751f\u6280\" \/>\n<meta property=\"og:url\" content=\"https:\/\/genomefrontier.com\/zh\/portfolio-item\/news012\/\" \/>\n<meta property=\"og:site_name\" content=\"GenomeFrontier Therapeutics, Inc. \u5148\u9a45\u751f\u6280\" \/>\n<meta property=\"article:modified_time\" content=\"2026-04-13T08:05:03+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/genomefrontier.com\\\/portfolio-item\\\/news012\\\/\",\"url\":\"https:\\\/\\\/genomefrontier.com\\\/portfolio-item\\\/news012\\\/\",\"name\":\"\u5148\u9a45\u751f\u6280\u591a\u9805\u767c\u660e \u7372\u570b\u969b\u95dc\u6ce8 \\\/ \u4e2d\u6642\u5831\u5c0e - GenomeFrontier Therapeutics, Inc. \u5148\u9a45\u751f\u6280\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/genomefrontier.com\\\/#website\"},\"datePublished\":\"2021-03-02T08:21:56+00:00\",\"dateModified\":\"2026-04-13T08:05:03+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/genomefrontier.com\\\/portfolio-item\\\/news012\\\/#breadcrumb\"},\"inLanguage\":\"zh-TW\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/genomefrontier.com\\\/portfolio-item\\\/news012\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/genomefrontier.com\\\/portfolio-item\\\/news012\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/genomefrontier.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u5148\u9a45\u751f\u6280\u591a\u9805\u767c\u660e \u7372\u570b\u969b\u95dc\u6ce8 \\\/ \u4e2d\u6642\u5831\u5c0e\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/genomefrontier.com\\\/#website\",\"url\":\"https:\\\/\\\/genomefrontier.com\\\/\",\"name\":\"GenomeFrontier Therapeutics, Inc. \u5148\u9a45\u751f\u6280\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/genomefrontier.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"zh-TW\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u5148\u9a45\u751f\u6280\u591a\u9805\u767c\u660e \u7372\u570b\u969b\u95dc\u6ce8 \/ \u4e2d\u6642\u5831\u5c0e - GenomeFrontier Therapeutics, Inc. \u5148\u9a45\u751f\u6280","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/genomefrontier.com\/zh\/portfolio-item\/news012\/","og_locale":"zh_TW","og_type":"article","og_title":"\u5148\u9a45\u751f\u6280\u591a\u9805\u767c\u660e \u7372\u570b\u969b\u95dc\u6ce8 \/ \u4e2d\u6642\u5831\u5c0e - GenomeFrontier Therapeutics, Inc. \u5148\u9a45\u751f\u6280","og_url":"https:\/\/genomefrontier.com\/zh\/portfolio-item\/news012\/","og_site_name":"GenomeFrontier Therapeutics, Inc. \u5148\u9a45\u751f\u6280","article_modified_time":"2026-04-13T08:05:03+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/genomefrontier.com\/portfolio-item\/news012\/","url":"https:\/\/genomefrontier.com\/portfolio-item\/news012\/","name":"\u5148\u9a45\u751f\u6280\u591a\u9805\u767c\u660e \u7372\u570b\u969b\u95dc\u6ce8 \/ \u4e2d\u6642\u5831\u5c0e - GenomeFrontier Therapeutics, Inc. \u5148\u9a45\u751f\u6280","isPartOf":{"@id":"https:\/\/genomefrontier.com\/#website"},"datePublished":"2021-03-02T08:21:56+00:00","dateModified":"2026-04-13T08:05:03+00:00","breadcrumb":{"@id":"https:\/\/genomefrontier.com\/portfolio-item\/news012\/#breadcrumb"},"inLanguage":"zh-TW","potentialAction":[{"@type":"ReadAction","target":["https:\/\/genomefrontier.com\/portfolio-item\/news012\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/genomefrontier.com\/portfolio-item\/news012\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/genomefrontier.com\/"},{"@type":"ListItem","position":2,"name":"\u5148\u9a45\u751f\u6280\u591a\u9805\u767c\u660e \u7372\u570b\u969b\u95dc\u6ce8 \/ \u4e2d\u6642\u5831\u5c0e"}]},{"@type":"WebSite","@id":"https:\/\/genomefrontier.com\/#website","url":"https:\/\/genomefrontier.com\/","name":"GenomeFrontier Therapeutics, Inc. \u5148\u9a45\u751f\u6280","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/genomefrontier.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"zh-TW"}]}},"_links":{"self":[{"href":"https:\/\/genomefrontier.com\/zh\/wp-json\/wp\/v2\/portfolio\/447","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/genomefrontier.com\/zh\/wp-json\/wp\/v2\/portfolio"}],"about":[{"href":"https:\/\/genomefrontier.com\/zh\/wp-json\/wp\/v2\/types\/portfolio"}],"author":[{"embeddable":true,"href":"https:\/\/genomefrontier.com\/zh\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/genomefrontier.com\/zh\/wp-json\/wp\/v2\/comments?post=447"}],"wp:attachment":[{"href":"https:\/\/genomefrontier.com\/zh\/wp-json\/wp\/v2\/media?parent=447"}],"wp:term":[{"taxonomy":"portfolio-types","embeddable":true,"href":"https:\/\/genomefrontier.com\/zh\/wp-json\/wp\/v2\/portfolio-types?post=447"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}